{"id":2901,"date":"2012-06-12T15:39:04","date_gmt":"2012-06-12T13:39:04","guid":{"rendered":"http:\/\/autoivresse.com\/blog\/?p=2901"},"modified":"2012-06-18T13:19:50","modified_gmt":"2012-06-18T11:19:50","slug":"le-mans-2012-tour-de-circuit-en-honda","status":"publish","type":"post","link":"https:\/\/autoivresse.com\/blog\/le-mans-2012-tour-de-circuit-en-honda\/","title":{"rendered":"Le Mans 2012 : Tour de circuit en Honda"},"content":{"rendered":"<p>On ne s&rsquo;en lace jamais. Voici un tour de circuit des 24 heures du Mans en Honda proto.<br \/>\nCeete video date de la journ\u00e9e d&rsquo;essai 2012:<\/p>\n<p><code><iframe loading=\"lazy\" src=\"http:\/\/www.youtube.com\/embed\/UiOk4Mf3AIE\" frameborder=\"0\" width=\"420\" height=\"315\"><\/iframe><\/code><\/p>\n","protected":false},"excerpt":{"rendered":"<p>On ne s&rsquo;en lace jamais. Voici un tour de circuit des 24 heures du Mans en Honda proto. Ceete video date de la journ\u00e9e d&rsquo;essai 2012:<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[4],"tags":[508,42,41,47,52,76,75,510,77,73,32,74],"class_list":["post-2901","post","type-post","status-publish","format-standard","hentry","category-24-heures","tag-24-heures","tag-24h","tag-24h-2012","tag-audi","tag-audi-1","tag-camera","tag-circuit","tag-course-auto","tag-embarquee","tag-honda","tag-le-mans","tag-tour-circuit"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/autoivresse.com\/blog\/wp-json\/wp\/v2\/posts\/2901","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/autoivresse.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/autoivresse.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/autoivresse.com\/blog\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/autoivresse.com\/blog\/wp-json\/wp\/v2\/comments?post=2901"}],"version-history":[{"count":0,"href":"https:\/\/autoivresse.com\/blog\/wp-json\/wp\/v2\/posts\/2901\/revisions"}],"wp:attachment":[{"href":"https:\/\/autoivresse.com\/blog\/wp-json\/wp\/v2\/media?parent=2901"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/autoivresse.com\/blog\/wp-json\/wp\/v2\/categories?post=2901"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/autoivresse.com\/blog\/wp-json\/wp\/v2\/tags?post=2901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}